{"id":20166,"date":"2020-12-14T22:48:56","date_gmt":"2020-12-14T21:48:56","guid":{"rendered":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/?post_type=product&#038;p=20166"},"modified":"2020-12-16T12:28:42","modified_gmt":"2020-12-16T11:28:42","slug":"sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2","status":"publish","type":"product","link":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/producto\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\/","title":{"rendered":"Sorbete de limones de S\u00f3ller &#8211;  tarrina 1\/2 litro"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Limones de S\u00f3ller.<\/p>\n","protected":false},"featured_media":20332,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[32],"product_tag":[109,163,162,179,181,176,180,173],"class_list":["post-20166","product","type-product","status-publish","has-post-thumbnail","product_cat-helados","product_tag-forn-pes-de-sa-palla","product_tag-helado-artesano","product_tag-helados","product_tag-limones","product_tag-limones-de-soller","product_tag-soller","product_tag-sorbete-de-limon","product_tag-sorbetes-naturales","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sorbete de limones de S\u00f3ller - tarrina 1\/2 litro - Cafe Palmanova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/para-llevar.esment.org\/cafe-palmanova\/producto\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sorbete de limones de S\u00f3ller - tarrina 1\/2 litro - Cafe Palmanova\" \/>\n<meta property=\"og:description\" content=\"Limones de S\u00f3ller.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/para-llevar.esment.org\/cafe-palmanova\/producto\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Cafe Palmanova\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/esmentcomunidad\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-16T11:28:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/para-llevar.esment.org\/cafe-palmanova\/wp-content\/uploads\/sites\/2\/2020\/12\/Helados5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@esmentcomunidad\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/producto\\\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\\\/\",\"url\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/producto\\\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\\\/\",\"name\":\"Sorbete de limones de S\u00f3ller - tarrina 1\\\/2 litro - Cafe Palmanova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/producto\\\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/producto\\\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/Helados5.jpg\",\"datePublished\":\"2020-12-14T21:48:56+00:00\",\"dateModified\":\"2020-12-16T11:28:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/producto\\\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/producto\\\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/producto\\\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/Helados5.jpg\",\"contentUrl\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/Helados5.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/producto\\\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sorbete de limones de S\u00f3ller &#8211; tarrina 1\\\/2 litro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/#website\",\"url\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/\",\"name\":\"Cafe Palmanova\",\"description\":\"Tienda Caf\u00e9 Palmanova\",\"publisher\":{\"@id\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/#organization\",\"name\":\"Cafe Palmanova\",\"url\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/logoAlimentacion.png\",\"contentUrl\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/logoAlimentacion.png\",\"width\":200,\"height\":50,\"caption\":\"Cafe Palmanova\"},\"image\":{\"@id\":\"https:\\\/\\\/para-llevar.esment.org\\\/cafe-palmanova\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/esmentcomunidad\",\"https:\\\/\\\/x.com\\\/esmentcomunidad\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/amadipesment\",\"https:\\\/\\\/www.instagram.com\\\/esmentalimentacio\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sorbete de limones de S\u00f3ller - tarrina 1\/2 litro - Cafe Palmanova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/producto\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\/","og_locale":"en_US","og_type":"article","og_title":"Sorbete de limones de S\u00f3ller - tarrina 1\/2 litro - Cafe Palmanova","og_description":"Limones de S\u00f3ller.","og_url":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/producto\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\/","og_site_name":"Cafe Palmanova","article_publisher":"https:\/\/www.facebook.com\/esmentcomunidad","article_modified_time":"2020-12-16T11:28:42+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/wp-content\/uploads\/sites\/2\/2020\/12\/Helados5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@esmentcomunidad","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/producto\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\/","url":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/producto\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\/","name":"Sorbete de limones de S\u00f3ller - tarrina 1\/2 litro - Cafe Palmanova","isPartOf":{"@id":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/#website"},"primaryImageOfPage":{"@id":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/producto\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\/#primaryimage"},"image":{"@id":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/producto\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\/#primaryimage"},"thumbnailUrl":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/wp-content\/uploads\/sites\/2\/2020\/12\/Helados5.jpg","datePublished":"2020-12-14T21:48:56+00:00","dateModified":"2020-12-16T11:28:42+00:00","breadcrumb":{"@id":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/producto\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/para-llevar.esment.org\/cafe-palmanova\/producto\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/producto\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\/#primaryimage","url":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/wp-content\/uploads\/sites\/2\/2020\/12\/Helados5.jpg","contentUrl":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/wp-content\/uploads\/sites\/2\/2020\/12\/Helados5.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/producto\/sorbete-de-fresas-mallorquinas-tarrina-1-2-litro-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/tienda\/"},{"@type":"ListItem","position":3,"name":"Sorbete de limones de S\u00f3ller &#8211; tarrina 1\/2 litro"}]},{"@type":"WebSite","@id":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/#website","url":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/","name":"Cafe Palmanova","description":"Tienda Caf\u00e9 Palmanova","publisher":{"@id":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/#organization","name":"Cafe Palmanova","url":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/#\/schema\/logo\/image\/","url":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/wp-content\/uploads\/sites\/2\/2020\/10\/logoAlimentacion.png","contentUrl":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/wp-content\/uploads\/sites\/2\/2020\/10\/logoAlimentacion.png","width":200,"height":50,"caption":"Cafe Palmanova"},"image":{"@id":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/esmentcomunidad","https:\/\/x.com\/esmentcomunidad","https:\/\/www.youtube.com\/user\/amadipesment","https:\/\/www.instagram.com\/esmentalimentacio\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/wp-json\/wp\/v2\/product\/20166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/wp-json\/wp\/v2\/media\/20332"}],"wp:attachment":[{"href":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/wp-json\/wp\/v2\/media?parent=20166"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/wp-json\/wp\/v2\/product_brand?post=20166"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/wp-json\/wp\/v2\/product_cat?post=20166"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/para-llevar.esment.org\/cafe-palmanova\/wp-json\/wp\/v2\/product_tag?post=20166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}